{"id":324518,"date":"2026-05-03T21:40:28","date_gmt":"2026-05-03T19:40:28","guid":{"rendered":"https:\/\/borncity.com\/blog\/?p=324518"},"modified":"2026-05-04T17:09:33","modified_gmt":"2026-05-04T15:09:33","slug":"microsoft-defender-blockt-digicert-root-zertifikate-als-trojanwin32-cerdigent-adha-3-mai-2026","status":"publish","type":"post","link":"https:\/\/borncity.com\/blog\/2026\/05\/03\/microsoft-defender-blockt-digicert-root-zertifikate-als-trojanwin32-cerdigent-adha-3-mai-2026\/","title":{"rendered":"Microsoft Defender blockt DigiCert-Root-Zertifikate als Trojan:Win32\/Cerdigent.A!dha (3. Mai 2026)"},"content":{"rendered":"<p><img decoding=\"async\" style=\"float: left; margin: 0px 10px 0px 0px; display: inline;\" title=\"Sicherheit (Pexels, allgemeine Nutzung)\" src=\"https:\/\/borncity.com\/blog\/wp-content\/uploads\/2021\/04\/Sicherheit_klein.jpg\" alt=\"Sicherheit (Pexels, allgemeine Nutzung)\" width=\"200\" align=\"left\" \/>Zum 3. Mai 2026 wurden eine Reihe Nutzer von Alarmen des Microsoft Defender unter Windows 11 aufgeschreckt. Der Defender hat diverse geblockte DigiCert-Zertifikate als <em>Trojan:Win32\/Cerdigent.A!dha<\/em> gemeldet. Der Hintergrund ist, dass DigiCert die Tage einige Zertifikate, die von Herstellern benutzt, aber von einer chinesischen Cybergruppe missbraucht wurden, zur\u00fcckgerufen (revoked) hat.<\/p>\n<p><!--more--><\/p>\n<h2>R\u00fcckblick auf das DigiCert-Zertifikate-Revoke<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vg08.met.vgwort.de\/na\/9ab6683528b541cbac4fb274eef53d47\" alt=\"\" width=\"1\" height=\"1\" \/>Vor einigen Tagen bin ich auf X \u00fcber die Information gestolpert, dass DigiCert Root-Zertifikate zur\u00fcckgerufen habe. Hintergrund ist, dass die chinesische Hackergruppe GoldenEyeDog (APT-Q-27) in der Lage war, EV-Zertifikate im Namen von Lenovo, Kingston, Shuttle Inc. und Palit Microsystems auszustellen und zur Signierung von Malware zu missbrauchen. Die Details sind in <a href=\"https:\/\/bugzilla.mozilla.org\/show_bug.cgi?id=2033170\" target=\"_blank\" rel=\"noopener\">diesem Mozilla Bug-Report<\/a> offen gelegt. Ich hatte im Blog-Beitrag <a href=\"https:\/\/borncity.com\/blog\/2026\/05\/03\/ev-zertifikate-von-lenovo-co-durch-goldeneyedog-missbraucht\/\">EV-Zertifikate von Lenovo &amp; Co. durch GoldenEyeDog missbraucht<\/a> auf den Sachverhalt hingewiesen.<\/p>\n<h2>Defender blockiert Zertifikate Trojan:Win32\/Cerdigent.A!dha<\/h2>\n<p>Mir ist das Thema in Kommentaren zum Beitrag <a href=\"https:\/\/borncity.com\/blog\/2026\/05\/03\/ev-zertifikate-von-lenovo-co-durch-goldeneyedog-missbraucht\/\">EV-Zertifikate von Lenovo &amp; Co. durch GoldenEyeDog missbraucht<\/a> sowie per Mail zugegangen.<\/p>\n<h3>Eine Nutzermeldung per Mail<\/h3>\n<p>Stephan hat mir heute Nachmittag eine E-Mail mit dem Betreff \"<em>Trojan:Win32\/ Cerdigent.A!dha: Vermutlich false positive<\/em>\" und der Botschaft \"<em>vielleicht interessiert Dich das hier f\u00fcr Deinen Blog<\/em>\" geschickt. Er schrieb, dass es \"heute Mittag\" bei Microsoft Defender-Systemen \"vereinzelt rot wurde\". Nach seinen bisherigen Recherchen handelt es sich vermutlich um \"false positives\".<\/p>\n<p>Das Defender-Update 1.449.424.0 brachte laut Leser die o.g. Signatur zur Erkennung von Trojan:Win32\/Cerdigent.A!dha mit, die angeblich zwei \"Root-Zertifikate von DigiCert\" als sch\u00e4dlich einstuft. Der Leser schrieb: \"Ich bin mir noch nicht sicher, aber auf mich wirkt es, als ob das ein Fehler ist, den Microsoft mit Defender-Update 1.449.425.0 behoben hat. Ich beobachte das noch eine kleine Weile, gehe aber von einem Fehlalarm aus. Auf Reddit finden sich bereits einige Thread und zahlreiche Leute, die betroffen sind.\"<\/p>\n<h3>Leserkommentare hier im Blog<\/h3>\n<p>In <a href=\"https:\/\/borncity.com\/blog\/2026\/05\/03\/ev-zertifikate-von-lenovo-co-durch-goldeneyedog-missbraucht\/#comment-254156\">diesem Kommentar<\/a> schreibt Chris, dass der Defender \"vor ein paar Minuten Windows Defender folgende zwei Zertifikate wegblockiert habe:<\/p>\n<p>rootcert: 0563B8630D62D75ABBC8AB1E4BDFB5A899B24D43rootcert: DDFB16CD4931C973A2037D3FC83A4D7D775D05E4<\/p>\n<p>Es wird eine Erkennung von \"Trojan:Win32\/Cerdigent.A!dha\" gemeldet. Das Thema werde bei reddit.com diskutiert.<\/p>\n<h3>Diskussionen bei Microsoft und reddit.com<\/h3>\n<p>Bei Microsoft Q&amp;A gibt es seit heute den Thread\u00a0<a href=\"https:\/\/learn.microsoft.com\/en-us\/answers\/questions\/5879116\/trojan-win32-cerdigent-a-dha\" target=\"_blank\" rel=\"noopener\">Trojan:Win32\/Cerdigent.A!dha<\/a>, wo jemand die oben genannte Warnung thematisiert. Nachfolgend ist die Defender-Meldung aus diesem Thread zu sehen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-324519\" src=\"https:\/\/borncity.com\/blog\/wp-content\/uploads\/2026\/05\/Defender-Alert.jpg\" alt=\"Defender Alert\" width=\"531\" height=\"539\" srcset=\"https:\/\/borncity.com\/blog\/wp-content\/uploads\/2026\/05\/Defender-Alert.jpg 531w, https:\/\/borncity.com\/blog\/wp-content\/uploads\/2026\/05\/Defender-Alert-296x300.jpg 296w\" sizes=\"auto, (max-width: 531px) 100vw, 531px\" \/><\/p>\n<p>Zahlreiche Nutzer best\u00e4tigen den gleichen Alarm des Defender. Ein Nutzer r\u00e4t, \"F\u00fchren Sie Windows Update aus. Dieses Problem wurde im neuesten Microsoft-Sicherheitsdefinitionsupdate 1.449.430.0 behoben.\" &#8211; die Trojaner-Signatur wird nicht mehr erkannt.<\/p>\n<p>Auf reddit.com finden sich z.B. <a href=\"https:\/\/www.reddit.com\/r\/techsupport\/comments\/1t2i5na\/trojan_detected_by_windows_security\/\" target=\"_blank\" rel=\"noopener\">dieser<\/a> und <a href=\"https:\/\/www.reddit.com\/r\/cybersecurity\/comments\/1t2hfsh\/mde_flagging_digi_cert_certificate_as_malicious\/\" target=\"_blank\" rel=\"noopener\">dieser<\/a> Thread mit der gleichen Thematik. Obiger R\u00fcckblick erkl\u00e4rt, warum Microsoft die beiden DigiCert-Zertifikate im Defender gesperrt hat. Die Funde gehen aber mutma\u00dflich in so gut wie allen F\u00e4llen nicht auf die Malware der chinesischen Hackergruppe GoldenEyeDog (APT-Q-27) zur\u00fcck geht.<\/p>\n<p><a href=\"https:\/\/x.com\/cyb3rops\/status\/2050920797464559930\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-324522\" src=\"https:\/\/borncity.com\/blog\/wp-content\/uploads\/2026\/05\/Defender-AlertRoth.jpg\" alt=\"Defender Alert Roth\" width=\"562\" height=\"659\" srcset=\"https:\/\/borncity.com\/blog\/wp-content\/uploads\/2026\/05\/Defender-AlertRoth.jpg 666w, https:\/\/borncity.com\/blog\/wp-content\/uploads\/2026\/05\/Defender-AlertRoth-255x300.jpg 255w\" sizes=\"auto, (max-width: 562px) 100vw, 562px\" \/><\/a><\/p>\n<p>Sicherheitsexperte Florian Roth weist in obigem <a href=\"https:\/\/x.com\/cyb3rops\/status\/2050920797464559930\" target=\"_blank\" rel=\"noopener\">Tweet<\/a> auf den gleichen Sachverhalt hin. Es bleibt aber das Problem, dass die oben genannten Zertifikate zur\u00fcckgerufen wurden, und dass die chinesische Cybergruppe ihre Malware mit diesen Zertifikaten signieren konnten. Die Malware sollte erkannt werden, ohne dass andere, legitime Software, die mit den gesperrten Zertifikaten signiert wurde, nicht irrt\u00fcmlich als Trojaner gemeldet wird.<\/p>\n<p>Erg\u00e4nzung: Die Kollegen von Bleeping Computer haben im Nachgang <a href=\"https:\/\/www.bleepingcomputer.com\/news\/security\/microsoft-defender-wrongly-flags-digicert-certs-as-trojan-win32-cerdigentadha\/\" target=\"_blank\" rel=\"noopener\">hier<\/a> die Geschichte ebenfalls entsprechend um Informationen erg\u00e4nzt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zum 3. Mai 2026 wurden eine Reihe Nutzer von Alarmen des Microsoft Defender unter Windows 11 aufgeschreckt. Der Defender hat diverse geblockte DigiCert-Zertifikate als Trojan:Win32\/Cerdigent.A!dha gemeldet. Der Hintergrund ist, dass DigiCert die Tage einige Zertifikate, die von Herstellern benutzt, aber &hellip; <a href=\"https:\/\/borncity.com\/blog\/2026\/05\/03\/microsoft-defender-blockt-digicert-root-zertifikate-als-trojanwin32-cerdigent-adha-3-mai-2026\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[161,301],"tags":[2699,24,4328,3288],"class_list":["post-324518","post","type-post","status-publish","format-standard","hentry","category-virenschutz","category-windows","tag-defender","tag-problem","tag-sicherheit","tag-windows-en"],"_links":{"self":[{"href":"https:\/\/borncity.com\/blog\/wp-json\/wp\/v2\/posts\/324518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/borncity.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/borncity.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/borncity.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/borncity.com\/blog\/wp-json\/wp\/v2\/comments?post=324518"}],"version-history":[{"count":7,"href":"https:\/\/borncity.com\/blog\/wp-json\/wp\/v2\/posts\/324518\/revisions"}],"predecessor-version":[{"id":324562,"href":"https:\/\/borncity.com\/blog\/wp-json\/wp\/v2\/posts\/324518\/revisions\/324562"}],"wp:attachment":[{"href":"https:\/\/borncity.com\/blog\/wp-json\/wp\/v2\/media?parent=324518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/borncity.com\/blog\/wp-json\/wp\/v2\/categories?post=324518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/borncity.com\/blog\/wp-json\/wp\/v2\/tags?post=324518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}