{"id":324916,"date":"2026-05-14T00:03:11","date_gmt":"2026-05-13T22:03:11","guid":{"rendered":"https:\/\/borncity.com\/blog\/?p=324916"},"modified":"2026-05-13T08:54:09","modified_gmt":"2026-05-13T06:54:09","slug":"patchday-microsoft-office-updates-12-mai-2026","status":"publish","type":"post","link":"https:\/\/borncity.com\/blog\/2026\/05\/14\/patchday-microsoft-office-updates-12-mai-2026\/","title":{"rendered":"Patchday: Microsoft Office Updates (12. Mai 2026)"},"content":{"rendered":"<p><img decoding=\"async\" style=\"margin: 0px 10px 0px 0px;\" title=\"Update\" src=\"https:\/\/borncity.com\/blog\/wp-content\/uploads\/2021\/06\/Update-01.jpg\" alt=\"Update\" align=\"left\" border=\"0\" \/>Am 12. Mai 2026 (zweiter Dienstag im Monat, Microsoft Patchday) hat Microsoft mehrere sicherheitsrelevante Updates f\u00fcr Microsoft Office ver\u00f6ffentlicht. Diesen Monat wurden gravierende Schwachstellen in Word geschlossen (siehe auch den Blog-Beitrag <a href=\"https:\/\/borncity.com\/blog\/2026\/05\/12\/microsoft-security-update-summary-12-mai-2026\/\">Microsoft Security Update Summary<\/a>\u00a0(12. Mai 2026)). Nachfolgend finden Sie eine Liste \u00fcber die verf\u00fcgbaren Updates.<\/p>\n<p><!--more--><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vg08.met.vgwort.de\/na\/4b327b9fc88a40d8b85db5ef29cd95d7\" alt=\"\" width=\"1\" height=\"1\" \/>Eine \u00dcbersicht \u00fcber die Updates finden Sie auf <a href=\"https:\/\/docs.microsoft.com\/en-us\/officeupdates\/office-updates-msi\" target=\"_blank\" rel=\"noopener\">dieser Webseite<\/a> (und <a href=\"https:\/\/support.microsoft.com\/help\/5092457\" target=\"_blank\" rel=\"noopener\">hier f\u00fcr diesen Monat<\/a>). Details sind in den verlinkten KB-Artikeln dokumentiert. Die Updates stehen f\u00fcr die installierbare MSI-Version von Microsoft Office bereit (die Click-to-Run-Pakete beziehen die Updates \u00fcber andere Kan\u00e4le).<\/p>\n<p>Microsoft Office 2019\/2021\/2024 erscheinen nicht in der Liste, da es \u00fcber Click-to-Run-Pakete verteilt wird und Sicherheitsupdates \u00fcber die Office Update-Funktion erh\u00e4lt.<\/p>\n<p>Microsoft Office 2016 und Microsoft Office 2019 sind zwar aus dem Support gefallen. Aber Microsoft hat diesen Monat noch Sicherheitsupdates ver\u00f6ffentlicht. Zuk\u00fcnftig hilft die 0patch-L\u00f6sung weiter (siehe <a href=\"https:\/\/borncity.com\/blog\/2025\/08\/27\/0patch-sichert-microsoft-office-2016-und-2019-nach-oktober-2025\/\" rel=\"bookmark\">0patch sichert Microsoft Office 2016 und 2019 nach Oktober 2025<\/a>).<\/p>\n<h2>Office 2016<\/h2>\n<p>Die folgenden Sicherheitsupdates wurden f\u00fcr Microsoft Office 2016 ver\u00f6ffentlicht.<\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li><a class=\"ocpArticleLink\" href=\"https:\/\/support.microsoft.com\/de-de\/topic\/beschreibung-des-sicherheitsupdates-f%C3%BCr-excel-2016-12-mai-2026-kb5002865-399c99bc-e62c-464e-971c-a2514b53d04c\" target=\"_blank\" rel=\"noopener\" data-bi-type=\"anchor\">KB5002865<\/a>: Sicherheitsupdate f\u00fcr Excel 2016, welches die Remote Code Execution (RCE) und Information Disclosure-Schwachstellen <a class=\"ocpExternalLink\" href=\"https:\/\/msrc.microsoft.com\/update-guide\/en-US\/vulnerability\/CVE-2026-40362\" target=\"_blank\" rel=\"noopener\" data-bi-type=\"anchor\">CVE-2026-40362<\/a>, <a class=\"ocpExternalLink\" href=\"https:\/\/msrc.microsoft.com\/update-guide\/en-US\/vulnerability\/CVE-2026-40359\" target=\"_blank\" rel=\"noopener\" data-bi-type=\"anchor\">CVE-2026-40359<\/a> und <a class=\"ocpExternalLink\" href=\"https:\/\/msrc.microsoft.com\/update-guide\/en-US\/vulnerability\/CVE-2026-40360\" target=\"_blank\" rel=\"noopener\" data-bi-type=\"anchor\">CVE-2026-40360<\/a>\u00a0schlie\u00dft.<\/li>\n<li><a class=\"ocpArticleLink\" href=\"https:\/\/support.microsoft.com\/de-de\/topic\/beschreibung-des-sicherheitsupdates-f%C3%BCr-office-2016-12-mai-2026-kb5002866-cef94511-1b8d-47a1-8988-ef72a218806e\" target=\"_blank\" rel=\"noopener\" data-bi-type=\"anchor\">KB5002866<\/a>: Sicherheitsupdate f\u00fcr Office 2016, welches die Remote Code Execution (RCE) Schwachstellen <a class=\"ocpExternalLink\" href=\"https:\/\/msrc.microsoft.com\/update-guide\/en-US\/vulnerability\/CVE-2026-40358\" target=\"_blank\" rel=\"noopener\" data-bi-type=\"anchor\">CVE-2026-40358<\/a> und <a class=\"ocpExternalLink\" href=\"https:\/\/msrc.microsoft.com\/update-guide\/en-US\/vulnerability\/CVE-2026-40363\" target=\"_blank\" rel=\"noopener\" data-bi-type=\"anchor\">CVE-2026-40363<\/a>\u00a0schlie\u00dft.<\/li>\n<li><a class=\"ocpArticleLink\" href=\"https:\/\/support.microsoft.com\/de-de\/topic\/beschreibung-des-sicherheitsupdates-f%C3%BCr-word-2016-12-mai-2026-kb5002858-42b9ef39-54e6-45e3-8184-192b6fbb802f\" target=\"_blank\" rel=\"noopener\" data-bi-type=\"anchor\">KB5002858<\/a>: Sicherheitsupdate f\u00fcr Word 2016, welches die Remote Code Execution (RCE) und Information Disclosure-Schwachstellen <a class=\"ocpExternalLink\" href=\"https:\/\/msrc.microsoft.com\/update-guide\/en-US\/vulnerability\/CVE-2026-40367\" target=\"_blank\" rel=\"noopener\" data-bi-type=\"anchor\">CVE-2026-40367<\/a>, <a class=\"ocpExternalLink\" href=\"https:\/\/msrc.microsoft.com\/update-guide\/en-US\/vulnerability\/CVE-2026-40421\" target=\"_blank\" rel=\"noopener\" data-bi-type=\"anchor\">CVE-2026-40421<\/a>, <a class=\"ocpExternalLink\" href=\"https:\/\/msrc.microsoft.com\/update-guide\/en-US\/vulnerability\/CVE-2026-35440\" target=\"_blank\" rel=\"noopener\" data-bi-type=\"anchor\">CVE-2026-35440<\/a>, <a class=\"ocpExternalLink\" href=\"https:\/\/msrc.microsoft.com\/update-guide\/en-US\/vulnerability\/CVE-2026-40361\" target=\"_blank\" rel=\"noopener\" data-bi-type=\"anchor\">CVE-2026-40361<\/a>, <a class=\"ocpExternalLink\" href=\"https:\/\/msrc.microsoft.com\/update-guide\/en-US\/vulnerability\/CVE-2026-40366\" target=\"_blank\" rel=\"noopener\" data-bi-type=\"anchor\">CVE-2026-40366<\/a> und <a class=\"ocpExternalLink\" href=\"https:\/\/msrc.microsoft.com\/update-guide\/en-US\/vulnerability\/CVE-2026-40364\" target=\"_blank\" rel=\"noopener\" data-bi-type=\"anchor\">CVE-2026-40364<\/a>\u00a0\u200b\u200b\u200b\u200b\u200b\u200b\u200b\u200b\u200b\u200b\u200b\u200b\u200b\u200b\u00a0schlie\u00dft.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>Amol Sarwate, Leiter der Sicherheitsforschung und des REDLab bei Cohesity sagt zu den Schwachstellen in Microsoft Word:<\/p>\n<blockquote><p>\"Die beiden Sicherheitsl\u00fccken CVE-2026-40361\/40364 im Vorschaufenster von Microsoft Office Word erfordern keine Benutzerinteraktion und k\u00f6nnen Remote ausgel\u00f6st werden, indem einfach ein sch\u00e4dliches Dokument per E-Mail versendet wird. Das Lesebereich von Outlook ist seit langem ein g\u00e4ngiger Angriffsvektor; eine einzige eingehende E-Mail kann die Ausnutzung der Schwachstelle ausl\u00f6sen, ohne dass der Benutzer sie jemals \u00f6ffnet.\"<\/p><\/blockquote>\n<p>Details zu den Office-Updates sowie die direkten Download-Adressen f\u00fcr die Updates sind den verlinkten KB-Artikeln zu entnehmen.<\/p>\n<h2>Office C2R-Updates<\/h2>\n<p>F\u00fcr die Click-2-Run-Installationspakete werden die Updates direkt \u00fcber das jeweilige Office-Paket bezogen und installiert. Gem\u00e4\u00df <a href=\"https:\/\/learn.microsoft.com\/en-us\/officeupdates\/microsoft365-apps-security-updates#may-12-2026\" target=\"_blank\" rel=\"noopener\">dieser Microsoft-Webseite<\/a> wurden folgende Sicherheitsupdates freigegeben:<\/p>\n<ul>\n<li>Current Channel: Version 2604 (Build 19929.20164)<\/li>\n<li>Monthly Enterprise Channel: Version 2604 (Build 19929.20162)<\/li>\n<li>Monthly Enterprise Channel: Version 2603 (Build 19822.20240)<\/li>\n<li>Monthly Enterprise Channel: Version 2602 (Build 19725.20320)<\/li>\n<li>Semi-Annual Enterprise Channel: Version 2508 (Build 19127.20646)<\/li>\n<li>Office 2024 Retail: Version 2604 (Build 19929.20164)<\/li>\n<li>Office 2021 Retail: Version 2604 (Build 19929.20164)<\/li>\n<li>Office LTSC 2024 Volume Licensed: Version 2408 (Build 17932.20776)<\/li>\n<li>Office LTSC 2021 Volume Licensed: Version 2108 (Build 14334.20670)<\/li>\n<li>Office 2019 Volume Licensed: Version 1808 (Build 10417.20132)<\/li>\n<\/ul>\n<p>Auf der oben verlinkten Webseite werden die beseitigten Sicherheitsl\u00fccken f\u00fcr einzelne Office-Module aufgelistet. F\u00fcr Volumenlizenzen (von Office 2024) werden die jeweiligen Builds auch auf <a href=\"https:\/\/learn.microsoft.com\/en-us\/officeupdates\/update-history-office-2024\" target=\"_blank\" rel=\"noopener\">dieser Microsoft-Seite<\/a> gelistet.<\/p>\n<h2>Updates f\u00fcr Office\/SharePoint Server<\/h2>\n<p>Microsoft hat au\u00dferdem Sicherheitsupdates f\u00fcr verschiedene Versionen von Microsoft SharePoint Server ver\u00f6ffentlicht. Hier wurden Spoofing-Schwachstellen publik, die als 0-day ausgenutzt werden (siehe auch den Blog-Beitrag <a href=\"https:\/\/borncity.com\/blog\/2026\/04\/14\/microsoft-security-update-summary-14-april-2026\/\">Microsoft Security Update Summary<\/a> (14. April 2026)).<\/p>\n<h3>SharePoint Server-Abonnementedition<\/h3>\n<ul>\n<li>SharePoint Server Subscription Edition: <a class=\"ocpArticleLink\" href=\"https:\/\/support.microsoft.com\/de-de\/topic\/beschreibung-des-sicherheitsupdates-f%C3%BCr-sharepoint-server-abonnementedition-12-mai-2026-kb5002863-91158c5e-7155-47f8-86c2-9f8924cbfa12\" target=\"_blank\" rel=\"noopener\" data-bi-type=\"anchor\">KB5002863<\/a><\/li>\n<\/ul>\n<h3>Microsoft SharePoint Server 2019<\/h3>\n<ul>\n<li>SharePoint Server 2019: <a class=\"ocpArticleLink\" href=\"https:\/\/support.microsoft.com\/de-de\/topic\/beschreibung-des-sicherheitsupdates-f%C3%BCr-sharepoint-server-2019-12-mai-2026-kb5002870-78ccf6f5-7506-42f1-b459-70c6d6d122da\" target=\"_blank\" rel=\"noopener\" data-bi-type=\"anchor\">KB5002870<\/a><\/li>\n<li>SharePoint Server 2019 Language Pack: <a class=\"ocpArticleLink\" href=\"https:\/\/support.microsoft.com\/de-de\/topic\/beschreibung-des-sicherheitsupdates-f%C3%BCr-sharepoint-server-2019-language-pack-12-mai-2026-kb5002872-915274b9-5d96-41d6-b2f7-414eacc9c9f4\" target=\"_blank\" rel=\"noopener\" data-bi-type=\"anchor\">KB5002872<\/a><\/li>\n<\/ul>\n<h3>Microsoft SharePoint Server 2016<\/h3>\n<ul>\n<li>SharePoint Enterprise Server 2016: <a class=\"ocpArticleLink\" href=\"https:\/\/support.microsoft.com\/de-de\/topic\/beschreibung-des-sicherheitsupdates-f%C3%BCr-sharepoint-server-2016-12-mai-2026-kb5002868-5cc10216-f312-4ded-86d2-4940b3a1fded\" target=\"_blank\" rel=\"noopener\" data-bi-type=\"anchor\">KB5002868<\/a><\/li>\n<li>SharePoint Server 2016 Language Pack: <a class=\"ocpArticleLink\" href=\"https:\/\/support.microsoft.com\/de-de\/topic\/beschreibung-des-sicherheitsupdates-f%C3%BCr-das-sharepoint-server-2016-sprachpaket-12-mai-2026-kb5002869-4c3be1d9-47e4-4a07-a972-084b6e050576\" target=\"_blank\" rel=\"noopener\" data-bi-type=\"anchor\">KB5002869<\/a><\/li>\n<\/ul>\n<h3>Office Online Server<\/h3>\n<ul>\n<li>Office Online Server: <a class=\"ocpArticleLink\" href=\"https:\/\/support.microsoft.com\/de-de\/topic\/beschreibung-des-sicherheitsupdates-f%C3%BCr-office-online-server-12-mai-2026-kb5002871-e2a33e57-d046-495c-9183-c12f6301b3df\" target=\"_blank\" rel=\"noopener\" data-bi-type=\"anchor\">KB5002871<\/a><\/li>\n<\/ul>\n<p><strong>\u00c4hnliche Artikel:<\/strong><br \/>\n<a href=\"https:\/\/borncity.com\/blog\/2026\/05\/12\/microsoft-security-update-summary-12-mai-2026\/\">Microsoft Security Update Summary<\/a>\u00a0(12. Mai 2026)<br \/>\n<a href=\"https:\/\/borncity.com\/blog\/2026\/05\/13\/patchday-windows-10-11-updates-12-mai-2026\/\">Patchday: Windows 10\/11 Updates<\/a>\u00a0(12. Mai 2026)<br \/>\n<a href=\"https:\/\/borncity.com\/blog\/2026\/05\/13\/patchday-windows-server-updates-12-mai-2026\/\">Patchday: Windows Server-Updates<\/a> (12. Mai 2026)<br \/>\n<a href=\"https:\/\/borncity.com\/blog\/2026\/05\/14\/patchday-microsoft-office-updates-12-mai-2026\/\">Patchday: Microsoft Office Updates<\/a> (12. Mai 2026)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am 12. Mai 2026 (zweiter Dienstag im Monat, Microsoft Patchday) hat Microsoft mehrere sicherheitsrelevante Updates f\u00fcr Microsoft Office ver\u00f6ffentlicht. Diesen Monat wurden gravierende Schwachstellen in Word geschlossen (siehe auch den Blog-Beitrag Microsoft Security Update Summary\u00a0(12. Mai 2026)). Nachfolgend finden Sie &hellip; <a href=\"https:\/\/borncity.com\/blog\/2026\/05\/14\/patchday-microsoft-office-updates-12-mai-2026\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[153,426,185],"tags":[4322,15594,7238,4328,4315],"class_list":["post-324916","post","type-post","status-publish","format-standard","hentry","category-microsoft-office","category-sicherheit","category-update","tag-office","tag-patchday-5-2026","tag-sharepoint","tag-sicherheit","tag-update"],"_links":{"self":[{"href":"https:\/\/borncity.com\/blog\/wp-json\/wp\/v2\/posts\/324916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/borncity.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/borncity.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/borncity.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/borncity.com\/blog\/wp-json\/wp\/v2\/comments?post=324916"}],"version-history":[{"count":4,"href":"https:\/\/borncity.com\/blog\/wp-json\/wp\/v2\/posts\/324916\/revisions"}],"predecessor-version":[{"id":324920,"href":"https:\/\/borncity.com\/blog\/wp-json\/wp\/v2\/posts\/324916\/revisions\/324920"}],"wp:attachment":[{"href":"https:\/\/borncity.com\/blog\/wp-json\/wp\/v2\/media?parent=324916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/borncity.com\/blog\/wp-json\/wp\/v2\/categories?post=324916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/borncity.com\/blog\/wp-json\/wp\/v2\/tags?post=324916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}